{"id":2071,"date":"2021-03-29T17:45:06","date_gmt":"2021-03-29T17:45:06","guid":{"rendered":"https:\/\/secrets-of-heaven.org\/secret-31\/"},"modified":"2021-05-05T20:06:41","modified_gmt":"2021-05-05T20:06:41","slug":"secret-31","status":"publish","type":"page","link":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/","title":{"rendered":"Secreto 31"},"content":{"rendered":"\r\n<p class=\"has-drop-cap wp-block-paragraph\">El mundo no puede sanar sus males, pues no conoce su remedio. Tampoco se perfeccionar\u00e1 hasta que lo que est\u00e1 m\u00e1s all\u00e1 del mundo se vuelva aceptable. Porque un mundo perfeccionado es como una puerta que se abre por s\u00ed misma. Mientras el mundo se busque como un lugar para el aislamiento, se mantendr\u00e1 en estado de caos para servir a ese prop\u00f3sito.<\/p>\r\n\r\n\r\n\r\n\r\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td width=33% class=\"has-text-align-center\" data-align=\"center\"><a class=\"arrow previous\" href=\"\/es\/secret-30\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/a><\/td><td width=33% class=\"has-text-align-center\" data-align=\"center\"><a href=\"..\/\">Inicio<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\"><a class=\"arrow next\" href=\"\/es\/secret-32\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/a><\/td><\/tr>\r\n<tr><td width=33% class=\"has-text-align-center\" data-align=\"center\">anterior<\/td><td><\/td><td class=\"has-text-align-center\" data-align=\"center\">pr\u00f3ximo<\/td><\/tr><\/tbody><\/table><\/figure>\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>El mundo no puede sanar sus males, pues no conoce su remedio. Tampoco se perfeccionar\u00e1 hasta que lo que est\u00e1 m\u00e1s all\u00e1 del mundo se vuelva aceptable. Porque un mundo perfeccionado es como una puerta que se abre por s\u00ed misma. Mientras el mundo se busque como un lugar para el aislamiento, se mantendr\u00e1 en&hellip; <a class=\"more-link\" href=\"https:\/\/secrets-of-heaven.org\/es\/secret-31\/\">Seguir leyendo <span class=\"screen-reader-text\">Secreto 31<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1996,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2071","page","type-page","status-publish","has-post-thumbnail","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secreto 31 - Secretos del Cielo<\/title>\n<meta name=\"description\" content=\"Secretos del Cielo es el comienzo de una comunicaci\u00f3n directa de Dios al coraz\u00f3n de la Creaci\u00f3n en cada uno de nosotros. Recibido por Marshall Vian Summers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/secrets-of-heaven.org\/es\/secret-31\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secreto 31 - Secretos del Cielo\" \/>\n<meta property=\"og:description\" content=\"Secretos del Cielo es el comienzo de una comunicaci\u00f3n directa de Dios al coraz\u00f3n de la Creaci\u00f3n en cada uno de nosotros. Recibido por Marshall Vian Summers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/secrets-of-heaven.org\/es\/secret-31\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretos del Cielo\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-05T20:06:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/secrets-of-heaven.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/secrets-of-heaven.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/\",\"url\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/\",\"name\":\"Secreto 31 - Secretos del Cielo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/secrets-of-heaven.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header-w-diamond-orange.jpg\",\"datePublished\":\"2021-03-29T17:45:06+00:00\",\"dateModified\":\"2021-05-05T20:06:41+00:00\",\"description\":\"Secretos del Cielo es el comienzo de una comunicaci\u00f3n directa de Dios al coraz\u00f3n de la Creaci\u00f3n en cada uno de nosotros. Recibido por Marshall Vian Summers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/#primaryimage\",\"url\":\"https:\\\/\\\/secrets-of-heaven.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header-w-diamond-orange.jpg\",\"contentUrl\":\"https:\\\/\\\/secrets-of-heaven.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header-w-diamond-orange.jpg\",\"width\":1058,\"height\":79},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/secret-31\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secreto 31\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/\",\"name\":\"Secretos del Cielo\",\"description\":\"ense\u00f1anzas misteriosas de los \u00e1ngeles\",\"publisher\":{\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/#organization\",\"name\":\"Secretos del Cielo\",\"url\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/secrets-of-heaven.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/secrets-twitter.png\",\"contentUrl\":\"https:\\\/\\\/secrets-of-heaven.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/secrets-twitter.png\",\"width\":1158,\"height\":682,\"caption\":\"Secretos del Cielo\"},\"image\":{\"@id\":\"https:\\\/\\\/secrets-of-heaven.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secreto 31 - Secretos del Cielo","description":"Secretos del Cielo es el comienzo de una comunicaci\u00f3n directa de Dios al coraz\u00f3n de la Creaci\u00f3n en cada uno de nosotros. Recibido por Marshall Vian Summers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/","og_locale":"es_ES","og_type":"article","og_title":"Secreto 31 - Secretos del Cielo","og_description":"Secretos del Cielo es el comienzo de una comunicaci\u00f3n directa de Dios al coraz\u00f3n de la Creaci\u00f3n en cada uno de nosotros. Recibido por Marshall Vian Summers.","og_url":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/","og_site_name":"Secretos del Cielo","article_modified_time":"2021-05-05T20:06:41+00:00","og_image":[{"width":626,"height":1000,"url":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/secrets-of-heaven.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/secrets-of-heaven.jpg","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/","url":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/","name":"Secreto 31 - Secretos del Cielo","isPartOf":{"@id":"https:\/\/secrets-of-heaven.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/#primaryimage"},"image":{"@id":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/#primaryimage"},"thumbnailUrl":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/header-w-diamond-orange.jpg","datePublished":"2021-03-29T17:45:06+00:00","dateModified":"2021-05-05T20:06:41+00:00","description":"Secretos del Cielo es el comienzo de una comunicaci\u00f3n directa de Dios al coraz\u00f3n de la Creaci\u00f3n en cada uno de nosotros. Recibido por Marshall Vian Summers.","breadcrumb":{"@id":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/secrets-of-heaven.org\/es\/secret-31\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/#primaryimage","url":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/header-w-diamond-orange.jpg","contentUrl":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/header-w-diamond-orange.jpg","width":1058,"height":79},{"@type":"BreadcrumbList","@id":"https:\/\/secrets-of-heaven.org\/es\/secret-31\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/secrets-of-heaven.org\/es\/"},{"@type":"ListItem","position":2,"name":"Secreto 31"}]},{"@type":"WebSite","@id":"https:\/\/secrets-of-heaven.org\/es\/#website","url":"https:\/\/secrets-of-heaven.org\/es\/","name":"Secretos del Cielo","description":"ense\u00f1anzas misteriosas de los \u00e1ngeles","publisher":{"@id":"https:\/\/secrets-of-heaven.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/secrets-of-heaven.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/secrets-of-heaven.org\/es\/#organization","name":"Secretos del Cielo","url":"https:\/\/secrets-of-heaven.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secrets-of-heaven.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/secrets-twitter.png","contentUrl":"https:\/\/secrets-of-heaven.org\/wp-content\/uploads\/2021\/03\/secrets-twitter.png","width":1158,"height":682,"caption":"Secretos del Cielo"},"image":{"@id":"https:\/\/secrets-of-heaven.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/pages\/2071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/comments?post=2071"}],"version-history":[{"count":1,"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/pages\/2071\/revisions"}],"predecessor-version":[{"id":2072,"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/pages\/2071\/revisions\/2072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/media\/1996"}],"wp:attachment":[{"href":"https:\/\/secrets-of-heaven.org\/es\/wp-json\/wp\/v2\/media?parent=2071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}